{"id":2132,"date":"2022-05-30T13:06:58","date_gmt":"2022-05-30T13:06:58","guid":{"rendered":"https:\/\/diario.madrid.es\/salamanca\/?p=2132"},"modified":"2022-05-30T13:06:58","modified_gmt":"2022-05-30T13:06:58","slug":"una-clase-magistral-de-10","status":"publish","type":"post","link":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/","title":{"rendered":"Una clase magistral de 10"},"content":{"rendered":"<p>El pasado s\u00e1bado los 30 afortunados que participaron en la <em>masterclass <\/em>gratuita impartida en los locales de ensayo Torrespa\u00f1a empezaron nerviosos ante este reto singular. Como si fuera parte de una de las grandes series americanas la clase estuvo capitaneada por el reconocido m\u00fasico Jos\u00e9 Mar\u00eda Guzm\u00e1n.<\/p>\n<p>Con una amplia andadura art\u00edstica Guzm\u00e1n hizo part\u00edcipe de su sabidur\u00eda musical a los asistentes. Con versiones de los Beatles u otros cl\u00e1sicos, esta <em>masterclass <\/em>ha supuesto un acercamiento a c\u00f3mo un artista consagrado trabaja diariamente. Trucos, c\u00f3mo moverse en el escenario y, lo m\u00e1s importante, saber controlar las emociones y pensar antes de actuar han sido algunos de los ejes de la jornada.<\/p>\n<div id='gallery-1' class='gallery galleryid-2132 gallery-columns-3 gallery-size-col-4-square'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1.jpeg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-500x500.jpeg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-1-2144\" srcset=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-500x500.jpeg 500w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-300x300.jpeg 300w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-1024x1024.jpeg 1024w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-150x150.jpeg 150w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-768x768.jpeg 768w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-1536x1536.jpeg 1536w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-1500x1500.jpeg 1500w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-1000x1000.jpeg 1000w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1-270x270.jpeg 270w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-2-1.jpeg 1600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-2144'>\n\t\t\t\tSesi\u00f3n pr\u00e1ctica con Jos\u00e9 Mar\u00eda Guzm\u00e1n como profe\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-28-at-11.41.28-AM.jpeg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-28-at-11.41.28-AM-500x500.jpeg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-1-2142\" srcset=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-28-at-11.41.28-AM-500x500.jpeg 500w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-28-at-11.41.28-AM-150x150.jpeg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-2142'>\n\t\t\t\tColocaci\u00f3n en el escenario\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM.jpeg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-500x500.jpeg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-1-2149\" srcset=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-500x500.jpeg 500w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-300x300.jpeg 300w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-1024x1024.jpeg 1024w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-150x150.jpeg 150w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-768x768.jpeg 768w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-1536x1536.jpeg 1536w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-1500x1500.jpeg 1500w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-1000x1000.jpeg 1000w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM-270x270.jpeg 270w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.56-PM.jpeg 1600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-2149'>\n\t\t\t\tDemostraci\u00f3n pr\u00e1ctica de Guzm\u00e1n\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Los m\u00fasicos han conocido la funci\u00f3n fundamental que la armon\u00eda de voces tiene para el trabajo en grupo, algo que se ha estado trabajando durante una parte de esta jornada. La coordinaci\u00f3n grupal es b\u00e1sica para el buen funcionamiento de la banda, ya que escuchar los acordes del resto de instrumentos y luego del sonido en conjunto es una de las claves para que la propuesta musical suene bien.<\/p>\n<p>Los participantes tambi\u00e9n han realizado un peque\u00f1o juego para conocer su o\u00eddo general: saber qu\u00e9 notas se tocaban en el teclado y la base r\u00edtmica de cada una.<\/p>\n<p>Adem\u00e1s, el alumnado ha comprobado la importancia de las t\u00e9cnicas para subirse al escenario y disfrutar del momento, demostrando la satisfacci\u00f3n que supone para un artista una actuaci\u00f3n, tanto en un gran escenario como en una peque\u00f1a sala. Un ejemplo claro son los famosos Los Ac\u00fasticos del Buenavista que se realizan la \u00faltima semana de mes en el distrito de Salamanca (ahora en par\u00f3n veraniego).<\/p>\n<div id='gallery-2' class='gallery galleryid-2132 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/whatsapp-image-2022-05-30-at-2-54-55-pm-5\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-2147\" srcset=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-150x150.jpeg 150w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-300x300.jpeg 300w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-1024x1024.jpeg 1024w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-768x768.jpeg 768w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-1536x1536.jpeg 1536w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-1500x1500.jpeg 1500w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-1000x1000.jpeg 1000w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-500x500.jpeg 500w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5-270x270.jpeg 270w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-5.jpeg 1600w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-2147'>\n\t\t\t\tLos participantes en los locales de ensayo Torrespa\u00f1a\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/whatsapp-image-2022-05-30-at-2-54-55-pm-4\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-4-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-2137\" srcset=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-4-150x150.jpeg 150w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-4-500x500.jpeg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-2137'>\n\t\t\t\tMomento de la masterclass\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/whatsapp-image-2022-05-30-at-2-54-55-pm-1-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-1-1-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-2143\" srcset=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-1-1-150x150.jpeg 150w, https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/WhatsApp-Image-2022-05-30-at-2.54.55-PM-1-1-500x500.jpeg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-2143'>\n\t\t\t\tColocaci\u00f3n en el escenario\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Al final de la masterclass, una actuaci\u00f3n en vivo y en directo con todos los asistentes como m\u00fasicos y como propios espectadores de una clase bien aprendida.<\/p>\n<p>Despu\u00e9s de esta clase magistral, los 30 \u2018iniciados\u2019 saben que, si quieren ensayar en los dos locales de la calle del Alcalde S\u00e1inz de Baranda 94, pueden solicitarlo de dos formas. A trav\u00e9s del correo electr\u00f3nico <a href=\"mailto:localensayosalamanca@madrid.es\">localensayosalamanca@madrid.es<\/a> o a trav\u00e9s del Whatsapp al tel\u00e9fono 647 991 826.<\/p>\n<p>\u00a1Qu\u00e9 no pare la m\u00fasica!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado, 30 m\u00fasicos pudieron disfrutar de una clase magistral de la mano de Jos\u00e9 Mar\u00eda Guzm\u00e1n. Con consejos, partituras y una parte pr\u00e1ctica, los asistentes han podido comprobar c\u00f3mo no es tan dif\u00edcil ser el rey del escenario.<\/p>\n","protected":false},"author":138,"featured_media":2151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[],"class_list":["post-2132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-participacion-ciudadana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v26.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una clase magistral de 10<\/title>\n<meta name=\"description\" content=\"El pasado s\u00e1bado, 30 m\u00fasicos pudieron disfrutar de una clase magistral de la mano de Jos\u00e9 Mar\u00eda Guzm\u00e1n. Con consejos, partituras y una parte pr\u00e1ctica, los asistentes han podido comprobar c\u00f3mo no es tan dif\u00edcil ser el rey del escenario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una clase magistral de 10\" \/>\n<meta property=\"og:description\" content=\"El pasado s\u00e1bado, 30 m\u00fasicos pudieron disfrutar de una clase magistral de la mano de Jos\u00e9 Mar\u00eda Guzm\u00e1n. Con consejos, partituras y una parte pr\u00e1ctica, los asistentes han podido comprobar c\u00f3mo no es tan dif\u00edcil ser el rey del escenario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Salamanca\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-30T13:06:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"evapascual\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JMDSalamanca\" \/>\n<meta name=\"twitter:site\" content=\"@JMDSalamanca\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"evapascual\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/\"},\"author\":{\"name\":\"evapascual\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45\"},\"headline\":\"Una clase magistral de 10\",\"datePublished\":\"2022-05-30T13:06:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/\"},\"wordCount\":401,\"publisher\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#organization\"},\"image\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg\",\"articleSection\":[\"Cultura\",\"Participaci\u00f3n Ciudadana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/\",\"url\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/\",\"name\":\"Una clase magistral de 10\",\"isPartOf\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg\",\"datePublished\":\"2022-05-30T13:06:58+00:00\",\"description\":\"El pasado s\u00e1bado, 30 m\u00fasicos pudieron disfrutar de una clase magistral de la mano de Jos\u00e9 Mar\u00eda Guzm\u00e1n. Con consejos, partituras y una parte pr\u00e1ctica, los asistentes han podido comprobar c\u00f3mo no es tan dif\u00edcil ser el rey del escenario.\",\"breadcrumb\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage\",\"url\":\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg\",\"contentUrl\":\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg\",\"width\":720,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diario.madrid.es\/salamanca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una clase magistral de 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#website\",\"url\":\"https:\/\/diario.madrid.es\/salamanca\/\",\"name\":\"Diario Madrid - Salamanca\",\"description\":\"Toda la informaci\u00f3n del distrito Salamanca\",\"publisher\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diario.madrid.es\/salamanca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#organization\",\"name\":\"Diario Madrid - Salamanca\",\"url\":\"https:\/\/diario.madrid.es\/salamanca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2025\/02\/Escudo-Ayuntamiento-Madrid.png\",\"contentUrl\":\"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2025\/02\/Escudo-Ayuntamiento-Madrid.png\",\"width\":1200,\"height\":675,\"caption\":\"Diario Madrid - Salamanca\"},\"image\":{\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/JMDSalamanca\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45\",\"name\":\"evapascual\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g\",\"caption\":\"evapascual\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una clase magistral de 10","description":"El pasado s\u00e1bado, 30 m\u00fasicos pudieron disfrutar de una clase magistral de la mano de Jos\u00e9 Mar\u00eda Guzm\u00e1n. Con consejos, partituras y una parte pr\u00e1ctica, los asistentes han podido comprobar c\u00f3mo no es tan dif\u00edcil ser el rey del escenario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/","og_locale":"es_ES","og_type":"article","og_title":"Una clase magistral de 10","og_description":"El pasado s\u00e1bado, 30 m\u00fasicos pudieron disfrutar de una clase magistral de la mano de Jos\u00e9 Mar\u00eda Guzm\u00e1n. Con consejos, partituras y una parte pr\u00e1ctica, los asistentes han podido comprobar c\u00f3mo no es tan dif\u00edcil ser el rey del escenario.","og_url":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/","og_site_name":"Salamanca","article_published_time":"2022-05-30T13:06:58+00:00","og_image":[{"width":720,"height":470,"url":"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg","type":"image\/jpeg"}],"author":"evapascual","twitter_card":"summary_large_image","twitter_creator":"@JMDSalamanca","twitter_site":"@JMDSalamanca","twitter_misc":{"Escrito por":"evapascual","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#article","isPartOf":{"@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/"},"author":{"name":"evapascual","@id":"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45"},"headline":"Una clase magistral de 10","datePublished":"2022-05-30T13:06:58+00:00","mainEntityOfPage":{"@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/"},"wordCount":401,"publisher":{"@id":"https:\/\/diario.madrid.es\/salamanca\/#organization"},"image":{"@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage"},"thumbnailUrl":"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg","articleSection":["Cultura","Participaci\u00f3n Ciudadana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/","url":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/","name":"Una clase magistral de 10","isPartOf":{"@id":"https:\/\/diario.madrid.es\/salamanca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage"},"image":{"@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage"},"thumbnailUrl":"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg","datePublished":"2022-05-30T13:06:58+00:00","description":"El pasado s\u00e1bado, 30 m\u00fasicos pudieron disfrutar de una clase magistral de la mano de Jos\u00e9 Mar\u00eda Guzm\u00e1n. Con consejos, partituras y una parte pr\u00e1ctica, los asistentes han podido comprobar c\u00f3mo no es tan dif\u00edcil ser el rey del escenario.","breadcrumb":{"@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#primaryimage","url":"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg","contentUrl":"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2022\/05\/destacada-1.jpg","width":720,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/diario.madrid.es\/salamanca\/2022\/05\/30\/una-clase-magistral-de-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diario.madrid.es\/salamanca\/"},{"@type":"ListItem","position":2,"name":"Una clase magistral de 10"}]},{"@type":"WebSite","@id":"https:\/\/diario.madrid.es\/salamanca\/#website","url":"https:\/\/diario.madrid.es\/salamanca\/","name":"Diario Madrid - Salamanca","description":"Toda la informaci\u00f3n del distrito Salamanca","publisher":{"@id":"https:\/\/diario.madrid.es\/salamanca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diario.madrid.es\/salamanca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diario.madrid.es\/salamanca\/#organization","name":"Diario Madrid - Salamanca","url":"https:\/\/diario.madrid.es\/salamanca\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/logo\/image\/","url":"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2025\/02\/Escudo-Ayuntamiento-Madrid.png","contentUrl":"https:\/\/diario.madrid.es\/salamanca\/wp-content\/uploads\/sites\/15\/2025\/02\/Escudo-Ayuntamiento-Madrid.png","width":1200,"height":675,"caption":"Diario Madrid - Salamanca"},"image":{"@id":"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/JMDSalamanca"]},{"@type":"Person","@id":"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45","name":"evapascual","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diario.madrid.es\/salamanca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g","caption":"evapascual"}}]}},"_links":{"self":[{"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/posts\/2132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":1,"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/posts\/2132\/revisions"}],"predecessor-version":[{"id":2150,"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/posts\/2132\/revisions\/2150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/media\/2151"}],"wp:attachment":[{"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/media?parent=2132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/categories?post=2132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diario.madrid.es\/salamanca\/wp-json\/wp\/v2\/tags?post=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}