{"id":5416,"date":"2022-07-14T08:24:40","date_gmt":"2022-07-14T08:24:40","guid":{"rendered":"https:\/\/diario.madrid.es\/centro\/?p=5416"},"modified":"2022-07-14T08:34:00","modified_gmt":"2022-07-14T08:34:00","slug":"mejorando-calles-plazas-y-equipamientos","status":"publish","type":"post","link":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/","title":{"rendered":"Mejorando calles, plazas y equipamientos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.<\/p>\n<p>Todo para conseguir mayor calidad de vida para los vecinos y\u2026 tambi\u00e9n para los visitantes porque no hay que olvidar que nuestro distrito es cita obligada para quien pisa Madrid. Te contamos aqu\u00ed m\u00e1s al detalle las obras<\/p>\n<p>Solamente en Malasa\u00f1a se van a invertir cerca de 970.000 euros para mejorar la accesibilidad en cinco de sus calles: Montserrat, Qui\u00f1ones, San Dimas, Acuerdo y Norte. Esta actuaci\u00f3n sigue el modelo empleado en la reforma del entorno de la calle de Santa Isabel el pasado a\u00f1o: convertir las actuales calles con calzada y aceras a distinto nivel en espacios de convivencia sin barreras arquitect\u00f3nicas, diferenciados solo por el tipo de pavimento, y no por desniveles que dificulten la movilidad de los transe\u00fantes.<\/p>\n<p><strong>Parques disfrutar del oto\u00f1o y\u2026 de todo el a\u00f1o<\/strong><\/p>\n<figure id=\"attachment_5426\" aria-describedby=\"caption-attachment-5426\" style=\"width: 379px\" class=\"wp-caption alignright\"><a href=\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/conservacion-idb-casino-de-la-reina\/\" rel=\"attachment wp-att-5426\"><img decoding=\"async\" class=\"wp-image-5426\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina.jpg\" alt=\"Casino de la Reina\" width=\"379\" height=\"238\" srcset=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina.jpg 1220w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina-300x188.jpg 300w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina-1024x643.jpg 1024w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina-768x482.jpg 768w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina-1000x628.jpg 1000w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina-500x314.jpg 500w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Conservacion-IDB-Casino-de-la-Reina-430x270.jpg 430w\" sizes=\"(max-width: 379px) 100vw, 379px\" \/><\/a><figcaption id=\"caption-attachment-5426\" class=\"wp-caption-text\">Casino de la Reina<\/figcaption><\/figure>\n<p>La Cornisa, el del Casino de la Reina, y el de Atenas, tres de los parques con solera del distrito, reciben un fuerte empuj\u00f3n inversor. En el primero, el de la Cornisa, la primera fase de su reforma requerir\u00e1 825.000 euros. Y en el primer semestre de 2023 se acometer\u00e1 la segunda.<\/p>\n<p>Las obras, adem\u00e1s renovar las instalaciones de alumbrado y de riego, trazar\u00e1n un nuevo \u2018mapa\u2019 de las zonas del parque seg\u00fan sus usos: plaza central; otras dos m\u00e1s, una soleada y otra de sombra, zona deportiva, \u00e1rea canina, mirador, huerto y zona infantil. Y, seg\u00fan su uso, variar\u00e1n los nuevos pavimentos: praderas de c\u00e9sped, losas de granito, terrizo, terrizo estabilizado, pavimento deportivo asf\u00e1ltico, l\u00e1mina de agua y gravilla de seguridad en la zona de juegos para ni\u00f1os.<\/p>\n<p>En el parque del Casino de la Reina se van a renovar las instalaciones del caf\u00e9 terraza y adecuar el quiosco, todo con un importe de 80.000 euros, y en el parque de Atenas se van a destinar 81.000 euros para instalar una zona de calistenia.<\/p>\n<p><strong>Plazas y calles m\u00e1s accesibles<\/strong><\/p>\n<p>En tres plazas muy singulares -Vara del Rey, la Corrala y Ministriles- se va a actuar en profundidad, para recuperar, en alguno de los casos, su configuraci\u00f3n inicial, mientras que en la de Santa B\u00e1rbara se adecuar\u00e1 el tradicional quiosco de flores.<\/p>\n<div id='gallery-1' class='gallery galleryid-5416 gallery-columns-3 gallery-size-col-4-square'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Proyecto-de-mejora-en-La-Corrala.jpg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Proyecto-de-mejora-en-La-Corrala-500x500.jpg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-1-5423\" srcset=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Proyecto-de-mejora-en-La-Corrala-500x500.jpg 500w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Proyecto-de-mejora-en-La-Corrala-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5423'>\n\t\t\t\tProyecto de mejora en La Corrala\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/plaza-General-Vara-del-Rey.jpg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/plaza-General-Vara-del-Rey-500x500.jpg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-1-5425\" srcset=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/plaza-General-Vara-del-Rey-500x500.jpg 500w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/plaza-General-Vara-del-Rey-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5425'>\n\t\t\t\tReforma de la plaza General Vara del Rey\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Remodelacion-en-Los-Ministriles.jpg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Remodelacion-en-Los-Ministriles-500x500.jpg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-1-5424\" srcset=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Remodelacion-en-Los-Ministriles-500x500.jpg 500w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Remodelacion-en-Los-Ministriles-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-5424'>\n\t\t\t\tRemodelaci\u00f3n de Los Ministriles\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>En este semestre comienzan las obras para remodelar la zona estancial y reorganizar los aparcamientos de la plaza del General Vara del Rey, en pleno Rastro. 620.000 euros en total para aportar m\u00e1s espacio y en mejores condiciones al peat\u00f3n, ya que se va a renovar el pavimento para mejorar la accesibilidad. En la calle del Amazonas se eliminar\u00e1n las plazas de estacionamiento e introducir\u00e1 arbolado en una de sus aceras. La mejora del ajardinamiento, sistemas de riego y mobiliario urbano completan los trabajos.<\/p>\n<p>En la remodelaci\u00f3n de la plaza de la Corrala se va a invertir cerca de medio mill\u00f3n de euros para recuperar su configuraci\u00f3n inicial y la conexi\u00f3n con la calle de Tribulete, eliminando la escalera y la rampa que conecta la plaza con esta calle y renovando el equipamiento urbano para introducir nuevos elementos que aumenten la actividad p\u00fablica en este espacio.<\/p>\n<p>Tambi\u00e9n en Lavapi\u00e9s, las obras en la plaza de Ministriles reordenar\u00e1n su topograf\u00eda para configurar el espacio de uso p\u00fablico en una \u00fanica plataforma situada al nivel de la calle de Lavapi\u00e9s, reordenando las escaleras e integrando las rampas en el dise\u00f1o para salvar la diferencia de cota con la calle de Ministriles. M\u00e1s de 420.000 euros en total que aportar\u00e1n, adem\u00e1s, nuevo equipamiento urbano, como los elementos de la zona de juegos infantil.<\/p>\n<p><strong>Mejoras en equipamientos<\/strong><\/p>\n<p>Tres escuelas infantiles y cinco colegios e institutos del distrito van a ver mejoradas y, a veces ampliadas, sus instalaciones durante el verano.<\/p>\n<p>En la Escuela Infantil El Duende (Palma, 36) se destinan 550.000 euros para sustituir los acabados interiores, adecuar las instalaciones de fontaner\u00eda, saneamiento, ventilaci\u00f3n y climatizaci\u00f3n e instalaci\u00f3n de un ascensor. En la de San Ant\u00f3n, Hortaleza, 63, se crear\u00e1 un cuarto de basuras, y se adecuar\u00e1n aseos, vestuarios, lavander\u00eda y almacenes, por importe de m\u00e1s de 44.000 euros. Finalmente, en la de Nuestra Se\u00f1ora de la Paloma y en el colegio aleda\u00f1o del mismo nombre, se destinan m\u00e1s de 128.000 euros para, entre otros trabajos, sustituir los acumuladores de agua caliente sanitaria (ACS), reparar humedades, inodoros infantiles y renovar la iluminaci\u00f3n.<\/p>\n<div id='gallery-2' class='gallery galleryid-5416 gallery-columns-3 gallery-size-col-4-square'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/EI-San-Anton.jpg'><img decoding=\"async\" width=\"473\" height=\"500\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/EI-San-Anton-473x500.jpg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-2-5419\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-5419'>\n\t\t\t\tEI San Ant\u00f3n\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/centros-educativos-plaza-Dos-de-Mayo.jpg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/centros-educativos-plaza-Dos-de-Mayo-500x500.jpg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-2-5418\" srcset=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/centros-educativos-plaza-Dos-de-Mayo-500x500.jpg 500w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/centros-educativos-plaza-Dos-de-Mayo-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-5418'>\n\t\t\t\tMejoras en centros educativos en la plaza Dos de Mayo\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/obras-de-conservacion-en-instalaciones-centro-educativo-La-Paloma.jpg'><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/obras-de-conservacion-en-instalaciones-centro-educativo-La-Paloma-500x500.jpg\" class=\"attachment-col-4-square size-col-4-square\" alt=\"\" aria-describedby=\"gallery-2-5420\" srcset=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/obras-de-conservacion-en-instalaciones-centro-educativo-La-Paloma-500x500.jpg 500w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/obras-de-conservacion-en-instalaciones-centro-educativo-La-Paloma-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-5420'>\n\t\t\t\tObras de conservacion en La Paloma\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>En los CEIP Santa Mar\u00eda y Pi i Margall se han consignado 171.000 y 147.000 euros, respectivamente, para renovar sus patios. Mientras que se destinan 365.000 y 174.000 euros para la subsanaci\u00f3n de deficiencias en los CEIP San Ildefonso y V\u00e1zquez de Mella, respectivamente.<\/p>\n<p><strong>Nuevo centro cultural y mejoras en instalaciones deportivas<\/strong><\/p>\n<p>El programa de obras incluye otras dotaciones como la sede de la junta municipal, Mayor, 72, donde se invertir\u00e1n 465.000 euros en adecuar puestos de trabajo, instalar iluminaci\u00f3n en fachada principal o sanear carpinter\u00edas de madera de balcones de primera planta y reparar los acabados. O como la rehabilitaci\u00f3n de la fachada de la Escuela de Arte Dram\u00e1tico, Escuela Infantil y Centro de Acogida, de Mej\u00eda Lequerica (369.000 euros) o la renovaci\u00f3n de la cubierta del Centro de Servicios Sociales Maravillas (100.000).<\/p>\n<figure id=\"attachment_5422\" aria-describedby=\"caption-attachment-5422\" style=\"width: 386px\" class=\"wp-caption alignright\"><a href=\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/adecuacion-espacios-para-el-cc-clara-del-rey\/\" rel=\"attachment wp-att-5422\"><img decoding=\"async\" class=\"wp-image-5422\" src=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey.jpg\" alt=\"Adecuaci\u00f3n instalaciones para el CC Clara del Rey\" width=\"386\" height=\"289\" srcset=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey.jpg 1123w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey-300x225.jpg 300w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey-1024x768.jpg 1024w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey-768x576.jpg 768w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey-1000x750.jpg 1000w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey-500x375.jpg 500w, https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/Adecuacion-espacios-para-el-CC-Clara-del-Rey-360x270.jpg 360w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/><\/a><figcaption id=\"caption-attachment-5422\" class=\"wp-caption-text\">Adecuaci\u00f3n instalaciones para el CC Clara del Rey<\/figcaption><\/figure>\n<p>Y otro importante monto econ\u00f3mico se lleva la reubicaci\u00f3n del Centro Cultural Clara del Rey en el edificio del Museo ABC, en Amaniel 29-31. El centro, que entrar\u00e1 en funcionamiento antes de final de a\u00f1o, aumenta con el traslado desde su actual ubicaci\u00f3n en la calle de La Palma, 36, 1.400 metros cuadrados de superficie. El presupuesto supera los 274.000 euros.<\/p>\n<p>Tambi\u00e9n se va a actuar en instalaciones deportivas b\u00e1sicas, como la de Nuestra Se\u00f1ora de la Paloma (52.000 euros para lograr espacios de sombra); Casino de la Reina, (15.000 euros para conservar elementos deportivos para mayores y gradas de la pista) y Conde Duque (casi 29.000 euros para mejorar alumbrado de pista, reparar el murete de cerramiento, sustituir porter\u00edas e instalar canastas de baloncesto).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.<\/p>\n","protected":false},"author":138,"featured_media":5417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v26.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mejorando calles, plazas y equipamientos<\/title>\n<meta name=\"description\" content=\"Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mejorando calles, plazas y equipamientos\" \/>\n<meta property=\"og:description\" content=\"Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-14T08:24:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-14T08:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"evapascual\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JMDCentro\" \/>\n<meta name=\"twitter:site\" content=\"@JMDCentro\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"evapascual\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/\"},\"author\":{\"name\":\"evapascual\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45\"},\"headline\":\"Mejorando calles, plazas y equipamientos\",\"datePublished\":\"2022-07-14T08:24:40+00:00\",\"dateModified\":\"2022-07-14T08:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/\"},\"wordCount\":1117,\"publisher\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/#organization\"},\"image\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/\",\"url\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/\",\"name\":\"Mejorando calles, plazas y equipamientos\",\"isPartOf\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg\",\"datePublished\":\"2022-07-14T08:24:40+00:00\",\"dateModified\":\"2022-07-14T08:34:00+00:00\",\"description\":\"Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.\",\"breadcrumb\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage\",\"url\":\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg\",\"contentUrl\":\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg\",\"width\":720,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diario.madrid.es\/centro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mejorando calles, plazas y equipamientos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/#website\",\"url\":\"https:\/\/diario.madrid.es\/centro\/\",\"name\":\"Diario Madrid - Centro\",\"description\":\"Noticias de la Junta Municipal del Distrito Centro\",\"publisher\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diario.madrid.es\/centro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/#organization\",\"name\":\"Diario Madrid - Centro\",\"url\":\"https:\/\/diario.madrid.es\/centro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2025\/02\/Escudo-Ayuntamiento-Madrid.png\",\"contentUrl\":\"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2025\/02\/Escudo-Ayuntamiento-Madrid.png\",\"width\":1200,\"height\":675,\"caption\":\"Diario Madrid - Centro\"},\"image\":{\"@id\":\"https:\/\/diario.madrid.es\/centro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/JMDCentro\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45\",\"name\":\"evapascual\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diario.madrid.es\/centro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g\",\"caption\":\"evapascual\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mejorando calles, plazas y equipamientos","description":"Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/","og_locale":"es_ES","og_type":"article","og_title":"Mejorando calles, plazas y equipamientos","og_description":"Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.","og_url":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/","og_site_name":"Centro","article_published_time":"2022-07-14T08:24:40+00:00","article_modified_time":"2022-07-14T08:34:00+00:00","og_image":[{"width":720,"height":470,"url":"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg","type":"image\/jpeg"}],"author":"evapascual","twitter_card":"summary_large_image","twitter_creator":"@JMDCentro","twitter_site":"@JMDCentro","twitter_misc":{"Escrito por":"evapascual","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#article","isPartOf":{"@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/"},"author":{"name":"evapascual","@id":"https:\/\/diario.madrid.es\/centro\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45"},"headline":"Mejorando calles, plazas y equipamientos","datePublished":"2022-07-14T08:24:40+00:00","dateModified":"2022-07-14T08:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/"},"wordCount":1117,"publisher":{"@id":"https:\/\/diario.madrid.es\/centro\/#organization"},"image":{"@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage"},"thumbnailUrl":"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/","url":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/","name":"Mejorando calles, plazas y equipamientos","isPartOf":{"@id":"https:\/\/diario.madrid.es\/centro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage"},"image":{"@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage"},"thumbnailUrl":"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg","datePublished":"2022-07-14T08:24:40+00:00","dateModified":"2022-07-14T08:34:00+00:00","description":"Centro afronta el segundo semestre de este a\u00f1o con ganas de renovaci\u00f3n. Casi seis millones y medio de euros va a invertir la junta municipal en mejorar el espacio p\u00fablico, haciendo m\u00e1s accesibles calles de barrios como Malasa\u00f1a, ganando espacio para el peat\u00f3n y mejorando las instalaciones de centros escolares, de servicios sociales o de mayores.","breadcrumb":{"@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#primaryimage","url":"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg","contentUrl":"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2022\/07\/destacada.jpg","width":720,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/diario.madrid.es\/centro\/2022\/07\/14\/mejorando-calles-plazas-y-equipamientos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diario.madrid.es\/centro\/"},{"@type":"ListItem","position":2,"name":"Mejorando calles, plazas y equipamientos"}]},{"@type":"WebSite","@id":"https:\/\/diario.madrid.es\/centro\/#website","url":"https:\/\/diario.madrid.es\/centro\/","name":"Diario Madrid - Centro","description":"Noticias de la Junta Municipal del Distrito Centro","publisher":{"@id":"https:\/\/diario.madrid.es\/centro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diario.madrid.es\/centro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diario.madrid.es\/centro\/#organization","name":"Diario Madrid - Centro","url":"https:\/\/diario.madrid.es\/centro\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diario.madrid.es\/centro\/#\/schema\/logo\/image\/","url":"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2025\/02\/Escudo-Ayuntamiento-Madrid.png","contentUrl":"https:\/\/diario.madrid.es\/centro\/wp-content\/uploads\/sites\/14\/2025\/02\/Escudo-Ayuntamiento-Madrid.png","width":1200,"height":675,"caption":"Diario Madrid - Centro"},"image":{"@id":"https:\/\/diario.madrid.es\/centro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/JMDCentro"]},{"@type":"Person","@id":"https:\/\/diario.madrid.es\/centro\/#\/schema\/person\/6f87f7dfbdec2384ee2c16609d028e45","name":"evapascual","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diario.madrid.es\/centro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9435a058d445539bcb89ce817ea6e16c6e44b699e277f4819e47a622d71adc6?s=96&d=mm&r=g","caption":"evapascual"}}]}},"_links":{"self":[{"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/posts\/5416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/comments?post=5416"}],"version-history":[{"count":3,"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/posts\/5416\/revisions"}],"predecessor-version":[{"id":5430,"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/posts\/5416\/revisions\/5430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/media\/5417"}],"wp:attachment":[{"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/media?parent=5416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/categories?post=5416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diario.madrid.es\/centro\/wp-json\/wp\/v2\/tags?post=5416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}